{"id":1032,"date":"2024-11-04T10:47:52","date_gmt":"2024-11-04T02:47:52","guid":{"rendered":"https:\/\/www.zegemfireplace.com\/?post_type=product&#038;p=1032"},"modified":"2024-11-04T10:48:48","modified_gmt":"2024-11-04T02:48:48","slug":"3000mm-length-hot-selling-3d-water-steam-vapor-electric-fireplace","status":"publish","type":"product","link":"https:\/\/www.zegemfireplace.com\/es\/producto\/3000mm-length-hot-selling-3d-water-steam-vapor-electric-fireplace\/","title":{"rendered":"3000mm de longitud venta caliente 3D chimenea el\u00e9ctrica de vapor de agua"},"content":{"rendered":"<div style=\"width: 1280px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1032-1\" width=\"1280\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1400mm-video.mp4?_=1\" \/><a href=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1400mm-video.mp4\">http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1400mm-video.mp4<\/a><\/video><\/div>\n<table>\n<tbody>\n<tr>\n<td width=\"286\">Modelo<\/td>\n<td width=\"359\">LD-3D-3000<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">M\u00e9todo de encendido<\/td>\n<td width=\"359\">encendido por descarga de baja tensi\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Modo de control<\/td>\n<td width=\"359\">mando a distancia<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Consumo de combustible<\/td>\n<td width=\"359\">Agua limpia<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Consumo de combustible<\/td>\n<td width=\"359\">1,66 litros\/H<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Capacidad del dep\u00f3sito de combusti\u00f3n<\/td>\n<td width=\"359\">20 litros<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Tiempo de combusti\u00f3n continuado<\/td>\n<td width=\"359\">12 horas<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Tama\u00f1o:L*A*A<\/td>\n<td width=\"359\">3000mmx280mmx200mm<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Tama\u00f1o del panel<\/td>\n<td width=\"359\">3000x280mm<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Tama\u00f1o de la bandeja de entrada<\/td>\n<td width=\"359\">2972x250mmx200mm<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">material<\/td>\n<td width=\"359\">Acero laminado en fr\u00edo<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Tama\u00f1o del envase<\/td>\n<td width=\"359\">3120mmx400mmx400mm<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">peso bruto<\/td>\n<td width=\"359\">90KG<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Configuraci\u00f3n est\u00e1ndar<\/td>\n<td width=\"359\">Pantalla t\u00e1ctil y mando a distancia<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Protecci\u00f3n autom\u00e1tica contra fallos de alimentaci\u00f3n, protecci\u00f3n contra cortocircuitos, segura y protegida<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Trabajo cronometrado, descanso cronometrado<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Mando a distancia por infrarrojos, c\u00f3modo y sencillo, sin molestias<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Control del nivel de combusti\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Alimentaci\u00f3n autom\u00e1tica de agua, funci\u00f3n autom\u00e1tica de drenaje de agua<\/td>\n<\/tr>\n<tr>\n<td width=\"286\"><\/td>\n<td width=\"359\">Los accesorios atomizados carecen de protecci\u00f3n contra el agua, detecci\u00f3n y apagado autom\u00e1ticos<\/td>\n<\/tr>\n<tr>\n<td width=\"286\">Funci\u00f3n opcional<\/td>\n<td width=\"359\">\u00a0sonido ardiente<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Modelo LD-3D-3000 M\u00e9todo de ignici\u00f3n de descarga de bajo voltaje Modo de control remoto Uso de combustible Agua limpia Consumo de combustible 1,66 litros\/H Capacidad del tanque de combusti\u00f3n 20 litros Tiempo de combusti\u00f3n continua 12 horas Tama\u00f1o:L*A*A 3000mmx280mmx200mm Tama\u00f1o del panel 3000x280mm Tama\u00f1o de la caja 2972x250mmx200mm Material Acero laminado en fr\u00edo Tama\u00f1o del paquete 3120mmx400mmx400mm Peso bruto 90KG Configuraci\u00f3n est\u00e1ndar Pantalla t\u00e1ctil y control remoto...<\/p>","protected":false},"featured_media":892,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":{"0":"post-1032","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-3d-water-fireplace","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple","12":"entry","13":"content-bg","14":"loop-entry"},"_links":{"self":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product\/1032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/comments?post=1032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/media\/892"}],"wp:attachment":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_brand?post=1032"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_cat?post=1032"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_tag?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}