{"id":806,"date":"2024-10-31T15:07:56","date_gmt":"2024-10-31T07:07:56","guid":{"rendered":"https:\/\/www.zegemfireplace.com\/?post_type=product&#038;p=806"},"modified":"2024-11-07T14:49:08","modified_gmt":"2024-11-07T06:49:08","slug":"outdoor-patio-wood-burning-fireplace","status":"publish","type":"product","link":"https:\/\/www.zegemfireplace.com\/es\/producto\/outdoor-patio-wood-burning-fireplace\/","title":{"rendered":"Chimenea de le\u00f1a para patio exterior"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-1204\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1-300x300.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1-150x150.png 150w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1-12x12.png 12w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1-100x100.png 100w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1724230008679-1.png 335w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"alignnone wp-image-831\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1730358157203-300x210.png\" alt=\"\" width=\"454\" height=\"318\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1730358157203-300x210.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1730358157203-18x12.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1730358157203-600x420.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1730358157203.png 742w\" sizes=\"(max-width: 454px) 100vw, 454px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Size\/mm diameter : 900\/1000\/1200\/1500 mm<\/p>\n<p>Height \/mm 400-580 mm adjustable<\/p>\n<p>Weight\/kg 100\/150\/180\/200<\/p>\n<p>Main material Double steel plate and vermiculite board<\/p>\n<p>Fuel Dry firewood<\/p>\n<p>Surface paint American Forest Heat Resistant Paint<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-811\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2-300x159.png\" alt=\"\" width=\"300\" height=\"159\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2-300x159.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2-768x407.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2-18x10.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2-600x318.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/1-2.png 820w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-812\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1-300x158.png\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1-300x158.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1-768x404.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1-18x9.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1-600x315.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/2-1.png 816w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-813\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1-300x273.png\" alt=\"\" width=\"300\" height=\"273\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1-300x273.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1-768x699.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1-13x12.png 13w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1-600x546.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/4-1.png 821w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-814\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1-300x205.png\" alt=\"\" width=\"300\" height=\"205\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1-300x205.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1-768x524.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1-18x12.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1-600x409.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/5-1.png 818w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-815\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6-300x155.png\" alt=\"\" width=\"300\" height=\"155\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6-300x155.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6-768x397.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6-18x9.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6-600x310.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/6.png 829w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-816\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7-300x160.png\" alt=\"\" width=\"300\" height=\"160\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7-300x160.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7-768x411.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7-18x10.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7-600x321.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/7.png 819w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-818\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2-300x172.png\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2-300x172.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2-768x441.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2-18x10.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2-600x345.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/12-2.png 813w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-819\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13-291x300.png\" alt=\"\" width=\"291\" height=\"300\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13-291x300.png 291w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13-768x791.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13-12x12.png 12w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13-600x618.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/13.png 805w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-820\" src=\"http:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14-300x151.png\" alt=\"\" width=\"300\" height=\"151\" srcset=\"https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14-300x151.png 300w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14-768x388.png 768w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14-18x9.png 18w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14-600x303.png 600w, https:\/\/www.zegemfireplace.com\/wp-content\/uploads\/2024\/10\/14.png 804w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Tama\u00f1o\/mm di\u00e1metro : 900\/1000\/1200\/1500 mm Altura \/mm 400-580 mm ajustable Peso\/kg 100\/150\/180\/200 Material principal Doble chapa de acero y tablero de vermiculita Combustible Le\u00f1a seca Pintura superficial Pintura resistente al calor American Forest &nbsp; \u00a0<\/p>","protected":false},"featured_media":1204,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[27,31],"product_tag":[],"class_list":{"0":"post-806","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outdoor-fireplace","7":"product_cat-wood-stove","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple","13":"entry","14":"content-bg","15":"loop-entry"},"_links":{"self":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product\/806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/comments?post=806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/media?parent=806"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_brand?post=806"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_cat?post=806"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.zegemfireplace.com\/es\/wp-json\/wp\/v2\/product_tag?post=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}